{"id":54014,"date":"2020-06-23T01:51:34","date_gmt":"2020-06-22T23:51:34","guid":{"rendered":"https:\/\/1001xxxpictures.com\/videos\/?p=54014"},"modified":"2020-06-23T01:51:34","modified_gmt":"2020-06-22T23:51:34","slug":"sara-jay-bella-maree-squirt-fest","status":"publish","type":"post","link":"https:\/\/1001xxxpictures.com\/videos\/live\/sara-jay-bella-maree-squirt-fest\/","title":{"rendered":"Sara Jay &#038; Bella Maree Squirt Fest"},"content":{"rendered":"<p>Bella Maree and Sara Jay getting banged by stud Porno Dan.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bella Maree and Sara Jay getting banged by stud Porno Dan.<\/p>\n","protected":false},"author":1,"featured_media":54015,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7311],"tags":[57,750,7312,1587,70,37],"actors":[7489,7313,1388],"class_list":["post-54014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-live","tag-hardcore","tag-huge-tits","tag-immorallive-com","tag-squirt","tag-threesome","tag-vibrator","actors-bella-maree","actors-porno-dan","actors-sara-jay"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sara Jay &amp; Bella Maree Squirt Fest<\/title>\n<meta name=\"description\" content=\"Bella Maree and Sara Jay getting banged by stud Porno Dan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/1001xxxpictures.com\/videos\/live\/sara-jay-bella-maree-squirt-fest\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sara Jay &amp; Bella Maree Squirt Fest\" \/>\n<meta property=\"og:description\" content=\"Bella Maree and Sara Jay getting banged by stud Porno Dan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/1001xxxpictures.com\/videos\/live\/sara-jay-bella-maree-squirt-fest\/\" \/>\n<meta property=\"og:site_name\" content=\"1001 XXX Pictures\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-22T23:51:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/1001xxxpictures.com\/videos\/wp-content\/uploads\/2020\/11\/29086_01_120sec_00.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"544\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"1001 XXX Pictures\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Sara Jay &amp; Bella Maree Squirt Fest\" \/>\n<meta name=\"twitter:description\" content=\"Bella Maree and Sara Jay getting banged by stud Porno Dan.\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"1001 XXX Pictures\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/live\\\/sara-jay-bella-maree-squirt-fest\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/live\\\/sara-jay-bella-maree-squirt-fest\\\/\"},\"author\":{\"name\":\"1001 XXX Pictures\",\"@id\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/#\\\/schema\\\/person\\\/e95e47f47383884ba5d99634dc569caf\"},\"headline\":\"Sara Jay &#038; Bella Maree Squirt Fest\",\"datePublished\":\"2020-06-22T23:51:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/live\\\/sara-jay-bella-maree-squirt-fest\\\/\"},\"wordCount\":17,\"publisher\":{\"@id\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/#\\\/schema\\\/person\\\/e95e47f47383884ba5d99634dc569caf\"},\"image\":{\"@id\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/live\\\/sara-jay-bella-maree-squirt-fest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/29086_01_120sec_00.jpg\",\"keywords\":[\"hardcore\",\"huge tits\",\"immorallive.com\",\"squirt\",\"threesome\",\"vibrator\"],\"articleSection\":[\"Live\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/live\\\/sara-jay-bella-maree-squirt-fest\\\/\",\"url\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/live\\\/sara-jay-bella-maree-squirt-fest\\\/\",\"name\":\"Sara Jay & Bella Maree Squirt Fest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/live\\\/sara-jay-bella-maree-squirt-fest\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/live\\\/sara-jay-bella-maree-squirt-fest\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/29086_01_120sec_00.jpg\",\"datePublished\":\"2020-06-22T23:51:34+00:00\",\"description\":\"Bella Maree and Sara Jay getting banged by stud Porno Dan.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/live\\\/sara-jay-bella-maree-squirt-fest\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/live\\\/sara-jay-bella-maree-squirt-fest\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/live\\\/sara-jay-bella-maree-squirt-fest\\\/#primaryimage\",\"url\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/29086_01_120sec_00.jpg\",\"contentUrl\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/29086_01_120sec_00.jpg\",\"width\":960,\"height\":544},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/live\\\/sara-jay-bella-maree-squirt-fest\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sara Jay &#038; Bella Maree Squirt Fest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/#website\",\"url\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/\",\"name\":\"1001 XXX Pictures\",\"description\":\"The Best Free XXX Porn Videos, Movies, Clips &amp; More!\",\"publisher\":{\"@id\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/#\\\/schema\\\/person\\\/e95e47f47383884ba5d99634dc569caf\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/1001xxxpictures.com\\\/videos\\\/#\\\/schema\\\/person\\\/e95e47f47383884ba5d99634dc569caf\",\"name\":\"1001 XXX Pictures\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d81bf06b21911c41072f51b30498b34ce42a38ad5e494ddab2f5fdec82f66e3b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d81bf06b21911c41072f51b30498b34ce42a38ad5e494ddab2f5fdec82f66e3b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d81bf06b21911c41072f51b30498b34ce42a38ad5e494ddab2f5fdec82f66e3b?s=96&d=mm&r=g\",\"caption\":\"1001 XXX Pictures\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d81bf06b21911c41072f51b30498b34ce42a38ad5e494ddab2f5fdec82f66e3b?s=96&d=mm&r=g\"},\"sameAs\":[\"https:\\\/\\\/1001xxxpictures.com\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sara Jay & Bella Maree Squirt Fest","description":"Bella Maree and Sara Jay getting banged by stud Porno Dan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/1001xxxpictures.com\/videos\/live\/sara-jay-bella-maree-squirt-fest\/","og_locale":"en_US","og_type":"article","og_title":"Sara Jay & Bella Maree Squirt Fest","og_description":"Bella Maree and Sara Jay getting banged by stud Porno Dan.","og_url":"https:\/\/1001xxxpictures.com\/videos\/live\/sara-jay-bella-maree-squirt-fest\/","og_site_name":"1001 XXX Pictures","article_published_time":"2020-06-22T23:51:34+00:00","og_image":[{"width":960,"height":544,"url":"https:\/\/1001xxxpictures.com\/videos\/wp-content\/uploads\/2020\/11\/29086_01_120sec_00.jpg","type":"image\/jpeg"}],"author":"1001 XXX Pictures","twitter_card":"summary_large_image","twitter_title":"Sara Jay & Bella Maree Squirt Fest","twitter_description":"Bella Maree and Sara Jay getting banged by stud Porno Dan.","twitter_misc":{"Written by":"1001 XXX Pictures"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/1001xxxpictures.com\/videos\/live\/sara-jay-bella-maree-squirt-fest\/#article","isPartOf":{"@id":"https:\/\/1001xxxpictures.com\/videos\/live\/sara-jay-bella-maree-squirt-fest\/"},"author":{"name":"1001 XXX Pictures","@id":"https:\/\/1001xxxpictures.com\/videos\/#\/schema\/person\/e95e47f47383884ba5d99634dc569caf"},"headline":"Sara Jay &#038; Bella Maree Squirt Fest","datePublished":"2020-06-22T23:51:34+00:00","mainEntityOfPage":{"@id":"https:\/\/1001xxxpictures.com\/videos\/live\/sara-jay-bella-maree-squirt-fest\/"},"wordCount":17,"publisher":{"@id":"https:\/\/1001xxxpictures.com\/videos\/#\/schema\/person\/e95e47f47383884ba5d99634dc569caf"},"image":{"@id":"https:\/\/1001xxxpictures.com\/videos\/live\/sara-jay-bella-maree-squirt-fest\/#primaryimage"},"thumbnailUrl":"https:\/\/1001xxxpictures.com\/videos\/wp-content\/uploads\/2020\/11\/29086_01_120sec_00.jpg","keywords":["hardcore","huge tits","immorallive.com","squirt","threesome","vibrator"],"articleSection":["Live"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/1001xxxpictures.com\/videos\/live\/sara-jay-bella-maree-squirt-fest\/","url":"https:\/\/1001xxxpictures.com\/videos\/live\/sara-jay-bella-maree-squirt-fest\/","name":"Sara Jay & Bella Maree Squirt Fest","isPartOf":{"@id":"https:\/\/1001xxxpictures.com\/videos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/1001xxxpictures.com\/videos\/live\/sara-jay-bella-maree-squirt-fest\/#primaryimage"},"image":{"@id":"https:\/\/1001xxxpictures.com\/videos\/live\/sara-jay-bella-maree-squirt-fest\/#primaryimage"},"thumbnailUrl":"https:\/\/1001xxxpictures.com\/videos\/wp-content\/uploads\/2020\/11\/29086_01_120sec_00.jpg","datePublished":"2020-06-22T23:51:34+00:00","description":"Bella Maree and Sara Jay getting banged by stud Porno Dan.","breadcrumb":{"@id":"https:\/\/1001xxxpictures.com\/videos\/live\/sara-jay-bella-maree-squirt-fest\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/1001xxxpictures.com\/videos\/live\/sara-jay-bella-maree-squirt-fest\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/1001xxxpictures.com\/videos\/live\/sara-jay-bella-maree-squirt-fest\/#primaryimage","url":"https:\/\/1001xxxpictures.com\/videos\/wp-content\/uploads\/2020\/11\/29086_01_120sec_00.jpg","contentUrl":"https:\/\/1001xxxpictures.com\/videos\/wp-content\/uploads\/2020\/11\/29086_01_120sec_00.jpg","width":960,"height":544},{"@type":"BreadcrumbList","@id":"https:\/\/1001xxxpictures.com\/videos\/live\/sara-jay-bella-maree-squirt-fest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/1001xxxpictures.com\/videos\/"},{"@type":"ListItem","position":2,"name":"Sara Jay &#038; Bella Maree Squirt Fest"}]},{"@type":"WebSite","@id":"https:\/\/1001xxxpictures.com\/videos\/#website","url":"https:\/\/1001xxxpictures.com\/videos\/","name":"1001 XXX Pictures","description":"The Best Free XXX Porn Videos, Movies, Clips &amp; More!","publisher":{"@id":"https:\/\/1001xxxpictures.com\/videos\/#\/schema\/person\/e95e47f47383884ba5d99634dc569caf"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/1001xxxpictures.com\/videos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/1001xxxpictures.com\/videos\/#\/schema\/person\/e95e47f47383884ba5d99634dc569caf","name":"1001 XXX Pictures","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d81bf06b21911c41072f51b30498b34ce42a38ad5e494ddab2f5fdec82f66e3b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d81bf06b21911c41072f51b30498b34ce42a38ad5e494ddab2f5fdec82f66e3b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d81bf06b21911c41072f51b30498b34ce42a38ad5e494ddab2f5fdec82f66e3b?s=96&d=mm&r=g","caption":"1001 XXX Pictures"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/d81bf06b21911c41072f51b30498b34ce42a38ad5e494ddab2f5fdec82f66e3b?s=96&d=mm&r=g"},"sameAs":["https:\/\/1001xxxpictures.com\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/1001xxxpictures.com\/videos\/wp-json\/wp\/v2\/posts\/54014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/1001xxxpictures.com\/videos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/1001xxxpictures.com\/videos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/1001xxxpictures.com\/videos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/1001xxxpictures.com\/videos\/wp-json\/wp\/v2\/comments?post=54014"}],"version-history":[{"count":0,"href":"https:\/\/1001xxxpictures.com\/videos\/wp-json\/wp\/v2\/posts\/54014\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/1001xxxpictures.com\/videos\/wp-json\/wp\/v2\/media\/54015"}],"wp:attachment":[{"href":"https:\/\/1001xxxpictures.com\/videos\/wp-json\/wp\/v2\/media?parent=54014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/1001xxxpictures.com\/videos\/wp-json\/wp\/v2\/categories?post=54014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/1001xxxpictures.com\/videos\/wp-json\/wp\/v2\/tags?post=54014"},{"taxonomy":"actors","embeddable":true,"href":"https:\/\/1001xxxpictures.com\/videos\/wp-json\/wp\/v2\/actors?post=54014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}